{"id":12749,"date":"2021-04-05T21:24:02","date_gmt":"2021-04-05T19:24:02","guid":{"rendered":"https:\/\/primjer6.canac.info\/?page_id=12749"},"modified":"2021-04-20T21:26:00","modified_gmt":"2021-04-20T19:26:00","slug":"zamjena-plombi","status":"publish","type":"page","link":"https:\/\/dentaloffice.ba\/en\/zamjena-plombi\/","title":{"rendered":"Zamjena plombi"},"content":{"rendered":"<p>[vc_row thsn-zindex=&#8221;2&#8243; full_width=&#8221;stretch_row&#8221; el_class=&#8221;thsn-overflow-visible&#8221; css=&#8221;.vc_custom_1563271081309{padding-top: 0px !important;}&#8221;][vc_column width=&#8221;5\/12&#8243; css=&#8221;.vc_custom_1563604882799{margin-top: 40px !important;}&#8221;]<div class=\"themesion-ele themesion-ele-pricing-table thsn-pricing-table-style-1\"><div  class=\"themesion-ptables-w wpb_content_element\"><div class=\"row multi-columns-row\"><div class=\"col-md-12\"><div class=\"thsn-pricing-table-box\">\r\n\t\t<h3 class=\"themesion-ptable-heading\">Zamjena plombi<\/h3><div class=\"themesion-sep\"><\/div>\t<div class=\"thsn-ptablebox-main-icon\"><i class=\"thsn-dentiq-icon thsn-dentiq-icon-tooth-2\"><\/i><\/div>\t<div class=\"themesion-ptable-price-w\">\r\n\t\t<div class=\"themesion-ptable-price\">110<\/div> <div class=\"themesion-ptable-symbol\">KM<\/div>\t\t<div class=\"themesion-ptable-frequency\">Paket<\/div>\t<\/div>\r\n\t<div class=\"thsn-ptable-lines-w\">\r\n\t\t<div class=\"thsn-ptable-line\"><i class=\"fa fa-check\"><\/i> Stomatolo\u0161ki pregled<\/div><div class=\"thsn-ptable-line\"><i class=\"fa fa-check\"><\/i> OPG snimak<\/div><div class=\"thsn-ptable-line\"><i class=\"fa fa-check\"><\/i> Tropovr\u0161inski ispun kompozit<\/div>\t<\/div>\t\r\n\t<\/div><\/div><\/div><\/div><\/div>[\/vc_column][vc_column thsn-zindex=&#8221;2&#8243; width=&#8221;7\/12&#8243; el_class=&#8221;thsn-contact-box&#8221; css=&#8221;.vc_custom_1563271208092{margin-top: -70px !important;}&#8221;]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f12748-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"12748\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/12749#wpcf7-f12748-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"12748\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f12748-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"thsn-main-form thsn-style-3\">\n\t<div class=\"row\">\n\t\t<div class=\"col-sm-6\">\n\t\t\t<div class=\"input-group\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Va\u0161e ime *\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-sm-6\">\n\t\t\t<div class=\"input-group\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-prezime\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Va\u0161e prezime *\" value=\"\" type=\"text\" name=\"your-prezime\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-sm-6\">\n\t\t\t<div class=\"input-group\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Va\u0161 Email *\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-sm-6\">\n\t\t\t<div class=\"input-group input-button\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Va\u0161 telefon *\" value=\"\" type=\"text\" name=\"your-phone\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-sm-12\">\n\t\t\t<div class=\"input-group input-button\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"message\"><textarea cols=\"40\" rows=\"5\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Poruka\" name=\"message\"><\/textarea><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-sm-12\">\n\t\t\t<div class=\"input-group input-button\">\n\t\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Po\u0161alji\" \/>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><input type='hidden' class='wpcf7-pum' value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}' \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row thsn-zindex=&#8221;2&#8243; full_width=&#8221;stretch_row&#8221; el_class=&#8221;thsn-overflow-visible&#8221; css=&#8221;.vc_custom_1563271081309{padding-top: 0px !important;}&#8221;][vc_column width=&#8221;5\/12&#8243; css=&#8221;.vc_custom_1563604882799{margin-top: 40px !important;}&#8221;][\/vc_column][vc_column thsn-zindex=&#8221;2&#8243; width=&#8221;7\/12&#8243; el_class=&#8221;thsn-contact-box&#8221; css=&#8221;.vc_custom_1563271208092{margin-top: -70px !important;}&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-12749","page","type-page","status-publish","hentry"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["ba","en"],"languages":{"ba":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zamjena plombi - Dental Office<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dentaloffice.ba\/zamjena-plombi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zamjena plombi - Dental Office\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dentaloffice.ba\/zamjena-plombi\/\" \/>\n<meta property=\"og:site_name\" content=\"Dental Office\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-20T19:26:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dentaloffice.ba\\\/zamjena-plombi\\\/\",\"url\":\"https:\\\/\\\/dentaloffice.ba\\\/zamjena-plombi\\\/\",\"name\":\"Zamjena plombi - Dental Office\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dentaloffice.ba\\\/#website\"},\"datePublished\":\"2021-04-05T19:24:02+00:00\",\"dateModified\":\"2021-04-20T19:26:00+00:00\",\"description\":\"Zamjena plombi - veoma povoljno i brza usluga s visokim kvalitetom\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dentaloffice.ba\\\/zamjena-plombi\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dentaloffice.ba\\\/zamjena-plombi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dentaloffice.ba\\\/zamjena-plombi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Po\u010detna\",\"item\":\"https:\\\/\\\/dentaloffice.ba\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zamjena plombi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dentaloffice.ba\\\/#website\",\"url\":\"https:\\\/\\\/dentaloffice.ba\\\/\",\"name\":\"Dental Office\",\"description\":\"Stomatolo\u0161ka ordinacija &quot;Dental Office&quot;\",\"publisher\":{\"@id\":\"https:\\\/\\\/dentaloffice.ba\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dentaloffice.ba\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dentaloffice.ba\\\/#organization\",\"name\":\"Dental Office\",\"url\":\"https:\\\/\\\/dentaloffice.ba\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dentaloffice.ba\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dentaloffice.ba\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/background-dental-office.png\",\"contentUrl\":\"https:\\\/\\\/dentaloffice.ba\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/background-dental-office.png\",\"width\":1200,\"height\":954,\"caption\":\"Dental Office\"},\"image\":{\"@id\":\"https:\\\/\\\/dentaloffice.ba\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zamjena plombi - Dental Office","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dentaloffice.ba\/zamjena-plombi\/","og_locale":"en_US","og_type":"article","og_title":"Zamjena plombi - Dental Office","og_url":"https:\/\/dentaloffice.ba\/zamjena-plombi\/","og_site_name":"Dental Office","article_modified_time":"2021-04-20T19:26:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dentaloffice.ba\/zamjena-plombi\/","url":"https:\/\/dentaloffice.ba\/zamjena-plombi\/","name":"Zamjena plombi - Dental Office","isPartOf":{"@id":"https:\/\/dentaloffice.ba\/#website"},"datePublished":"2021-04-05T19:24:02+00:00","dateModified":"2021-04-20T19:26:00+00:00","description":"Zamjena plombi - veoma povoljno i brza usluga s visokim kvalitetom","breadcrumb":{"@id":"https:\/\/dentaloffice.ba\/zamjena-plombi\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dentaloffice.ba\/zamjena-plombi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dentaloffice.ba\/zamjena-plombi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Po\u010detna","item":"https:\/\/dentaloffice.ba\/"},{"@type":"ListItem","position":2,"name":"Zamjena plombi"}]},{"@type":"WebSite","@id":"https:\/\/dentaloffice.ba\/#website","url":"https:\/\/dentaloffice.ba\/","name":"Dental Office","description":"Stomatolo\u0161ka ordinacija &quot;Dental Office&quot;","publisher":{"@id":"https:\/\/dentaloffice.ba\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dentaloffice.ba\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dentaloffice.ba\/#organization","name":"Dental Office","url":"https:\/\/dentaloffice.ba\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dentaloffice.ba\/#\/schema\/logo\/image\/","url":"https:\/\/dentaloffice.ba\/wp-content\/uploads\/2021\/12\/background-dental-office.png","contentUrl":"https:\/\/dentaloffice.ba\/wp-content\/uploads\/2021\/12\/background-dental-office.png","width":1200,"height":954,"caption":"Dental Office"},"image":{"@id":"https:\/\/dentaloffice.ba\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dentaloffice.ba\/en\/wp-json\/wp\/v2\/pages\/12749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dentaloffice.ba\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dentaloffice.ba\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dentaloffice.ba\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dentaloffice.ba\/en\/wp-json\/wp\/v2\/comments?post=12749"}],"version-history":[{"count":0,"href":"https:\/\/dentaloffice.ba\/en\/wp-json\/wp\/v2\/pages\/12749\/revisions"}],"wp:attachment":[{"href":"https:\/\/dentaloffice.ba\/en\/wp-json\/wp\/v2\/media?parent=12749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}